{"id":7642,"date":"2021-07-28T13:23:47","date_gmt":"2021-07-28T11:23:47","guid":{"rendered":"https:\/\/skrivanek.com\/interpretacion\/"},"modified":"2026-03-26T12:14:40","modified_gmt":"2026-03-26T11:14:40","slug":"interpretacion","status":"publish","type":"page","link":"https:\/\/skrivanek.com\/es\/interpretacion\/","title":{"rendered":"Interpretaci\u00f3n"},"content":{"rendered":"<div id=\"pl-7642\"  class=\"panel-layout\" ><div id=\"pg-7642-0\"  class=\"panel-grid panel-has-style\" ><div class=\"siteorigin-panels-stretch panel-row-padding-none panel-row-style panel-row-style-for-7642-0\" data-stretch-type=\"full\" ><div id=\"pgc-7642-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-7642-0-0-0\" class=\"so-panel widget widget_wpa9-editor-ext panel-first-child\" data-index=\"0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-wpa9-editor-ext so-widget-wpa9-editor-ext-default-c93e1481a745-7642\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h2 style=\"text-align: center;\">Servicios de interpretaci\u00f3n<\/h2>\n<\/div>\n<\/div><\/div><div id=\"panel-7642-0-0-1\" class=\"so-panel widget widget_wpa9-card-m panel-last-child\" data-index=\"1\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-wpa9-card-m so-widget-wpa9-card-m-default-c93e1481a745-7642\"\n\t\t\t\n\t\t>\n\n<section class=\"wpa9-card wpa9-card-m-container d-flex flex-wrap justify-content-center dfEC0T\">\n\n\t\n\t\t\n\t\t\t\n\t<article class=\"wpa9-card-m-panel wpa9-panel \">\n\t<a class=\"rounded\" href=\"\/es\/interpretacion\/interpretacion-de-conferencias\/\" title=\"Interpretaci\u00f3n de conferencias\">\n\t\t\t\t<header class=\"d-block flex-wrap pb-4\">\n\t\t\t\t\t\t\t<span class=\"wpa9-card-icon icon d-none\" style=\"background-image: url('https:\/\/skrivanek.com\/wp-content\/uploads\/2021\/03\/ico-online-vyuka.svg')\"><\/span>\n\t\t\t\t<span class=\"wpa9-card-icon icon\" style=\"mask-image: url(https:\/\/skrivanek.com\/wp-content\/uploads\/2021\/03\/ico-online-vyuka.svg); -webkit-mask-image: url(https:\/\/skrivanek.com\/wp-content\/uploads\/2021\/03\/ico-online-vyuka.svg);\"><\/span>\n\t\t\t\n\t\t\t\t\t\t\t\t<h2 class=\"wpa9-card-title\">Interpretaci\u00f3n de conferencias<\/h2>\n\t\t\t\t<\/header>\n\n\t\t\t\t<main class=\"wpa9-card-content\"><p>Trabaje con un socio de interpretaci\u00f3n que abarca m\u00e1s de 40 idiomas en varias combinaciones y que proporciona int\u00e9rpretes expertos donde los\u00a0necesite.<\/p>\n<\/main>\n\t\t\n\t<\/a>\t<\/article>\n\t\t\n\t\t\t\n\t<article class=\"wpa9-card-m-panel wpa9-panel \">\n\t<a class=\"rounded\" href=\"\/es\/interpretacion\/interpretacion-de-reuniones-de-negocios\/\" title=\"Interpretaci\u00f3n de reuniones de negocios\">\n\t\t\t\t<header class=\"d-block flex-wrap pb-4\">\n\t\t\t\t\t\t\t<span class=\"wpa9-card-icon icon d-none\" style=\"background-image: url('https:\/\/skrivanek.com\/wp-content\/uploads\/2021\/03\/ico-jazykove-zkousky.svg')\"><\/span>\n\t\t\t\t<span class=\"wpa9-card-icon icon\" style=\"mask-image: url(https:\/\/skrivanek.com\/wp-content\/uploads\/2021\/03\/ico-jazykove-zkousky.svg); -webkit-mask-image: url(https:\/\/skrivanek.com\/wp-content\/uploads\/2021\/03\/ico-jazykove-zkousky.svg);\"><\/span>\n\t\t\t\n\t\t\t\t\t\t\t\t<h2 class=\"wpa9-card-title\">Interpretaci\u00f3n de reuniones de negocios<\/h2>\n\t\t\t\t<\/header>\n\n\t\t\t\t<main class=\"wpa9-card-content\"><p>Con nuestro gran equipo de int\u00e9rpretes profesionales y experimentados, los asistentes a sus reuniones hablar\u00e1n el mismo idioma sin necesidad de conocerlo realmente.<\/p>\n<\/main>\n\t\t\n\t<\/a>\t<\/article>\n\t\t\n\t\t\t\n\t<article class=\"wpa9-card-m-panel wpa9-panel \">\n\t<a class=\"rounded\" href=\"\/es\/interpretacion\/interpretacion-en-juzgados\/\" title=\"Interpretaci\u00f3n en juzgados\">\n\t\t\t\t<header class=\"d-block flex-wrap pb-4\">\n\t\t\t\t\t\t\t<span class=\"wpa9-card-icon icon d-none\" style=\"background-image: url('https:\/\/skrivanek.com\/wp-content\/uploads\/2021\/03\/ico-tlumoceni-soudni.svg')\"><\/span>\n\t\t\t\t<span class=\"wpa9-card-icon icon\" style=\"mask-image: url(https:\/\/skrivanek.com\/wp-content\/uploads\/2021\/03\/ico-tlumoceni-soudni.svg); -webkit-mask-image: url(https:\/\/skrivanek.com\/wp-content\/uploads\/2021\/03\/ico-tlumoceni-soudni.svg);\"><\/span>\n\t\t\t\n\t\t\t\t\t\t\t\t<h2 class=\"wpa9-card-title\">Interpretaci\u00f3n en juzgados<\/h2>\n\t\t\t\t<\/header>\n\n\t\t\t\t<main class=\"wpa9-card-content\"><p>Este tipo de interpretaci\u00f3n requiere una gran precisi\u00f3n, independencia e imparcialidad. Los int\u00e9rpretes deben tener un compromiso firme con estos\u00a0principios.<\/p>\n<\/main>\n\t\t\n\t<\/a>\t<\/article>\n\t\t\n\t\t\t\n\t<article class=\"wpa9-card-m-panel wpa9-panel \">\n\t<a class=\"rounded\" href=\"\/es\/interpretacion\/interpretacion-remota\/\" title=\"Interpretaci\u00f3n remota\">\n\t\t\t\t<header class=\"d-block flex-wrap pb-4\">\n\t\t\t\t\t\t\t<span class=\"wpa9-card-icon icon d-none\" style=\"background-image: url('https:\/\/skrivanek.com\/wp-content\/uploads\/2021\/03\/ico-telefonicka-vyuka.svg')\"><\/span>\n\t\t\t\t<span class=\"wpa9-card-icon icon\" style=\"mask-image: url(https:\/\/skrivanek.com\/wp-content\/uploads\/2021\/03\/ico-telefonicka-vyuka.svg); -webkit-mask-image: url(https:\/\/skrivanek.com\/wp-content\/uploads\/2021\/03\/ico-telefonicka-vyuka.svg);\"><\/span>\n\t\t\t\n\t\t\t\t\t\t\t\t<h2 class=\"wpa9-card-title\">Interpretaci\u00f3n remota<\/h2>\n\t\t\t\t<\/header>\n\n\t\t\t\t<main class=\"wpa9-card-content\"><p>La moderna tecnolog\u00eda de comunicaci\u00f3n nos permite interpretar presentaciones y sesiones de formaci\u00f3n a trav\u00e9s del tel\u00e9fono o de videoconferencias para que la comunicaci\u00f3n sea\u00a0constante.<\/p>\n<\/main>\n\t\t\n\t<\/a>\t<\/article>\n\t\t\n\t\t\t\n\t<article class=\"wpa9-card-m-panel wpa9-panel \">\n\t<a class=\"rounded\" href=\"\/es\/interpretacion\/moderador-de-reuniones-virtuales\/\" title=\"Moderador de reuniones virtuales\">\n\t\t\t\t<header class=\"d-block flex-wrap pb-4\">\n\t\t\t\t\t\t\t<span class=\"wpa9-card-icon icon d-none\" style=\"background-image: url('https:\/\/skrivanek.com\/wp-content\/uploads\/2021\/03\/ico-e-learning.svg')\"><\/span>\n\t\t\t\t<span class=\"wpa9-card-icon icon\" style=\"mask-image: url(https:\/\/skrivanek.com\/wp-content\/uploads\/2021\/03\/ico-e-learning.svg); -webkit-mask-image: url(https:\/\/skrivanek.com\/wp-content\/uploads\/2021\/03\/ico-e-learning.svg);\"><\/span>\n\t\t\t\n\t\t\t\t\t\t\t\t<h2 class=\"wpa9-card-title\">Moderador de reuniones virtuales<\/h2>\n\t\t\t\t<\/header>\n\n\t\t\t\t<main class=\"wpa9-card-content\"><p class=\"entry-subtitle border-top-c-green\">Las reuniones en l\u00ednea son realmente importantes... cuando funcionan. Las sesiones de teleconferencia pueden ser sencillas, menos costosas porque eliminan los gastos de transporte y mucho m\u00e1s eficaces.<\/p>\n<\/main>\n\t\t\n\t<\/a>\t<\/article>\n\t\t\n\n\t\t\n\t\n<\/section>\n<\/div><\/div><\/div><\/div><\/div><div id=\"pg-7642-1\"  class=\"panel-grid panel-has-style\" ><div class=\"panel-row-padding-none panel-row-style panel-row-style-for-7642-1\" ><div id=\"pgc-7642-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-7642-1-0-0\" class=\"so-panel widget widget_wpa9-editor-ext panel-first-child panel-last-child\" data-index=\"2\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-wpa9-editor-ext so-widget-wpa9-editor-ext-default-c93e1481a745-7642\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h3>\u00bfPor qu\u00e9 elegir Skrivanek para servicios de interpretaci\u00f3n?<\/h3>\n<h4><img decoding=\"async\" class=\"alignnone wp-image-85870\" src=\"https:\/\/skrivanek.com\/wp-content\/uploads\/2024\/05\/ico-needle.svg\" alt=\"tailored to your needs\" width=\"30\" \/> Soluciones flexibles y escalables, adaptadas a sus necesidades<\/h4>\n<p>Ya sea que necesite interpretaci\u00f3n para una reuni\u00f3n individual o una gran conferencia internacional, ofrecemos soluciones flexibles que se adaptan a sus requisitos. Nuestros servicios pueden ajustarse a eventos de cualquier tama\u00f1o o complejidad.<\/p>\n<h4><img decoding=\"async\" class=\"alignnone wp-image-253\" src=\"https:\/\/skrivanek.com\/wp-content\/uploads\/2021\/01\/ico-soudnipreklad.svg\" alt=\"icon court translation \/ certification\" width=\"30\" \/> Calidad certificada<\/h4>\n<p data-start=\"265\" data-end=\"471\">Nuestros servicios de interpretaci\u00f3n cumplen con los m\u00e1s altos est\u00e1ndares internacionales. Skrivanek cuenta con m\u00faltiples certificaciones ISO, lo que garantiza una calidad constante, seguridad de los datos y procesos profesionales en los que puede confiar.<\/p>\n<p data-start=\"473\" data-end=\"555\"><a href=\"https:\/\/skrivanek.com\/es\/sobre-nosotros\/certificaciones-iso\/\">Consulte nuestros certificados ISO<\/a><\/p>\n<h4><img decoding=\"async\" class=\"alignnone wp-image-251\" src=\"https:\/\/skrivanek.com\/wp-content\/uploads\/2021\/01\/ico-odbornypreklad.svg\" alt=\"icon medical translation\" width=\"30\" \/> Especializaci\u00f3n por sectores<\/h4>\n<p>Nuestros int\u00e9rpretes est\u00e1n altamente cualificados en diversos \u00e1mbitos, incluidos el legal, t\u00e9cnico, m\u00e9dico y otros. Comprendemos las particularidades de cada sector, lo que garantiza precisi\u00f3n y profesionalidad en cada interpretaci\u00f3n.<\/p>\n<h4><img decoding=\"async\" class=\"alignnone wp-image-3825\" src=\"https:\/\/skrivanek.com\/wp-content\/uploads\/2021\/03\/ico-seznam.svg\" alt=\"icon checklist languages\" width=\"30\" \/> Cobertura ling\u00fc\u00edstica global<\/h4>\n<p>Con una red de int\u00e9rpretes que dominan m\u00e1s de 110 idiomas, estamos preparados para cubrir sus necesidades, independientemente de su ubicaci\u00f3n o del idioma requerido. Desde idiomas poco comunes hasta los m\u00e1s hablados, lo tenemos cubierto.<\/p>\n<h4><img alt=\"languages\" loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-89548\" src=\"https:\/\/skrivanek.com\/wp-content\/uploads\/2024\/10\/languages.png\" alt=\"\" width=\"30\" height=\"30\" \/> Disponibilidad en todo el mundo<\/h4>\n<p>Nuestro equipo global est\u00e1 disponible las 24 horas del d\u00eda, garantizando que, independientemente de su zona horaria o de sus necesidades de interpretaci\u00f3n, siempre tenga acceso a int\u00e9rpretes profesionales cuando y donde los necesite.<\/p>\n<\/div>\n<\/div><\/div><\/div><div id=\"pgc-7642-1-1\"  class=\"panel-grid-cell\" ><div id=\"panel-7642-1-1-0\" class=\"so-panel widget widget_wpforms-widget wpforms-widget panel-first-child\" data-index=\"3\" ><h3 class=\"widget-title\">P\u00f3ngase en contacto con nosotros y encontraremos la soluci\u00f3n de interpretaci\u00f3n perfecta para usted.<\/h3>\r\n<style type=\"text\/css\">\r\n\r\n\r\n\r\nbody #wpforms-91405 {\r\n\t\t\r\n\t\t\tfont-family:inherit;}\r\n\r\n\t\r\n\r\n\tbody #wpforms-91405 .wpforms-head-container {\r\n\t\tborder-width: 0px;}\r\n\r\n\tbody #wpforms-91405 .wpforms-head-container .wpforms-title {\r\n\t\t}\r\n\r\n\tbody #wpforms-91405 .wpforms-head-container .wpforms-description {\r\n\t\t\t\tdisplay:block;\r\n\t}\r\n\r\n\r\n\tbody #wpforms-91405 .wpforms-submit-container .wpforms-submit, body #wpforms-91405 .wpforms-field-pagebreak button.wpforms-page-button {\r\n\t\tcolor:#ffffff ;background-color:#ff643b ;border-width:0px ;border-style:solid ;border-radius:10px ;-web-border-radius:10px ;-moz-border-radius:10px ;\t\t\t}\r\n\r\n\tbody #wpforms-91405 .wpforms-submit-container .wpforms-submit:hover, body #wpforms-91405 .wpforms-field-pagebreak button.wpforms-page-button:hover {\r\n\tbackground-color:;\tcolor:;\t}\r\n\r\n\tbody #wpforms-91405 .wpforms-submit-container,\r\n\tbody #wpforms-91405 .wpforms-field-pagebreak .wpforms-pagebreak-left{\r\n\t\t}\r\n\r\n\r\n\tbody #wpforms-91405 .wpforms-form .wpforms-field input[type=text],\r\n\tbody #wpforms-91405 .wpforms-form .wpforms-field input[type=email],\r\n\tbody #wpforms-91405 .wpforms-form .wpforms-field input[type=tel],\r\n\tbody #wpforms-91405 .wpforms-form .wpforms-field input[type=url],\r\n\tbody #wpforms-91405 .wpforms-form .wpforms-field input[type=password],\r\n\tbody #wpforms-91405 .wpforms-form .wpforms-field input[type=number]\r\n\t{\r\n\t\tborder-width:1px ;border-style:solid ;\t\t\t}\r\n\r\n\tbody #wpforms-91405 .wpforms-form .wpforms-field .wpforms-field-row\r\n\t{\r\n\t\t\t}\r\n\r\n\tbody #wpforms-91405 .wpforms-form .wpforms-field-layout.wpforms-field input[type=text],\r\n\tbody #wpforms-91405 .wpforms-form .wpforms-field-layout.wpforms-field input[type=email],\r\n\tbody #wpforms-91405 .wpforms-form .wpforms-field-layout.wpforms-field input[type=tel],\r\n\tbody #wpforms-91405 .wpforms-form .wpforms-field-layout.wpforms-field input[type=url],\r\n\tbody #wpforms-91405 .wpforms-form .wpforms-field-layout.wpforms-field input[type=password],\r\n\tbody #wpforms-91405 .wpforms-form .wpforms-field-layout.wpforms-field input[type=number]{\r\n\t\twidth: 100%;\r\n\t}\r\n\r\n\tbody #wpforms-91405 .wpforms-form .wpforms-field .wpforms-field-row input[type=text]{\r\n\t\twidth: 100%;\r\n\t}\r\n\r\n\r\n\r\n\t#wpforms-91405 .wpforms-form .wpforms-field-layout-rows,\r\n\t#wpforms-91405 .wpforms-form .wpforms-field-layout-columns{\r\n\t\t\t}\r\n\r\n\r\n\r\n\tbody #wpforms-91405 .wpforms-form .wpforms-field textarea {\r\n\t\t\t\t\tborder-width: 1px;\t}\r\n\r\n \r\n\r\n\tbody #wpforms-91405 .wpforms-form .wpforms-field select {\r\n\r\n\t\t\r\n\t\tborder-width: 1px;\t}\r\n\r\n\t\/* dropdown styles on modern background *\/\r\n\tbody #wpforms-91405 .wpforms-form .wpforms-field-select-style-modern .choices__inner{\r\n\t\t\t\t\r\n\t}\r\n\r\n\t\/* background color on modern dropdown *\/\r\n\t\r\n \r\n\tbody #wpforms-91405 .wpforms-form .wpforms-field-radio li label,\r\n\tbody #wpforms-91405 .wpforms-form .wpforms-field-payment-multiple li label {\r\n\t\t\t}\r\n \r\n\tbody #wpforms-91405 .wpforms-form .wpforms-field-checkbox li label {\r\n\t\t\t}\r\n \r\n\tbody #wpforms-91405 .wpforms-form .wpforms-field .wpforms-field-description {\r\n\r\n\t\t\t}\r\n\r\n \r\n\tbody #wpforms-91405 .wpforms-form .wpforms-field label.wpforms-field-label,\r\n\tbody #wpforms-91405 .wpforms-form .wpforms-field .wpforms-field-label {\r\n\t\tfont-weight: bold;\t}\r\n\r\n\r\n \r\n\tbody #wpforms-confirmation-91405  {\r\n\r\n\t\t\t\tborder-width: 1px;\t}\r\n\r\n\tbody #wpforms-confirmation-91405 p{\r\n\t\ttext-transform: uppercase;\r\n\t\ttext-decoration: underline;\r\n\t\tcolor: inherit;\r\n\t}\r\n\r\n \r\n\tbody #wpforms-91405 label.wpforms-error,\r\n\tbody #wpforms-91405 .wpforms-error[role=\"alert\"] {\r\n\t\t\r\n\t\t\t\tborder-width: 1px;\t}\r\n\/* Styling for Tablets *\/\r\n@media only screen and (max-width: 800px) and (min-width:481px) {\r\n\t\r\n\r\n\r\n\r\n}\r\n\r\n@media only screen and (max-width: 480px){\r\n\t\r\n\r\n\r\n\r\n}\r\n\/*Option to add custom CSS *\/\r\n\r\n\r\n\r\n\t\t<\/style>\r\n\t\t<div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-91405\"><form id=\"wpforms-form-91405\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"91405\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/es\/wp-json\/wp\/v2\/pages\/7642?wpforms_form_id=91405\" data-token=\"5faa322d6a6b35524677ccf7327df918\" data-token-time=\"1788353943\"><noscript class=\"wpforms-error-noscript\">Por favor, activa JavaScript en tu navegador para completar este formulario.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Por favor, activa JavaScript en tu navegador para completar este formulario.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-91405-field_7-container\" class=\"wpforms-field wpforms-field-layout\" data-field-id=\"7\"><div class=\"wpforms-field-layout-rows wpforms-field-large\"><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-91405-field_2-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-91405-field_2\">Su nombre <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-91405-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" aria-errormessage=\"wpforms-91405-field_2-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-91405-field_1-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-91405-field_1\">Nombre de la empresa<\/label><input type=\"text\" id=\"wpforms-91405-field_1\" class=\"wpforms-field-medium\" name=\"wpforms[fields][1]\" aria-errormessage=\"wpforms-91405-field_1-error\" ><\/div><\/div><\/div><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-91405-field_5-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-91405-field_5\">Correo electr\u00f3nico <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-91405-field_5\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][5]\" spellcheck=\"false\" aria-errormessage=\"wpforms-91405-field_5-error\" required><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-91405-field_6-container\" class=\"wpforms-field wpforms-field-phone\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-91405-field_6\">Tel\u00e9fono<\/label><input type=\"tel\" id=\"wpforms-91405-field_6\" class=\"wpforms-field-medium wpforms-smart-phone-field\" data-rule-smart-phone-field=\"true\" name=\"wpforms[fields][6]\" aria-label=\"Tel\u00e9fono\" aria-errormessage=\"wpforms-91405-field_6-error\" ><\/div><\/div><\/div><div class=\"wpforms-layout-row\"><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-91405-field_3-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-91405-field_3\">Detalles de la consulta<\/label><textarea id=\"wpforms-91405-field_3\" class=\"wpforms-field-medium\" name=\"wpforms[fields][3]\" aria-errormessage=\"wpforms-91405-field_3-error\" ><\/textarea><\/div><\/div><div class=\"wpforms-layout-column wpforms-layout-column-50\"><div id=\"wpforms-91405-field_10-container\" class=\"wpforms-field wpforms-field-file-upload\" data-field-id=\"10\"><label class=\"wpforms-field-label\" for=\"wpforms-91405-field_10\">Carga de archivos<\/label><div\n\t\tclass=\"wpforms-uploader \"\n\t\tdata-field-id=\"10\"\n\t\tdata-form-id=\"91405\"\n\t\tdata-input-name=\"wpforms_91405_10\"\n\t\tdata-extensions=\"jpg,jpeg,jpe,gif,png,bmp,tiff,tif,webp,avif,ico,heic,heif,heics,heifs,asf,asx,wmv,wmx,wm,avi,divx,mov,qt,mpeg,mpg,mpe,mp4,m4v,ogv,webm,mkv,3gp,3gpp,3g2,3gp2,txt,asc,c,cc,h,srt,csv,tsv,ics,rtx,css,vtt,mp3,m4a,m4b,aac,ra,ram,wav,x-wav,ogg,oga,flac,mid,midi,wma,wax,mka,rtf,pdf,class,tar,zip,gz,gzip,rar,7z,psd,xcf,doc,pot,pps,ppt,wri,xla,xls,xlt,xlw,mpp,docx,docm,dotx,dotm,xlsx,xlsm,xlsb,xltx,xltm,xlam,pptx,pptm,ppsx,ppsm,potx,potm,ppam,sldx,sldm,onetoc,onetoc2,onepkg,oxps,xps,odt,odp,ods,odg,odc,odb,odf,wp,wpd,key,numbers,pages,svg\"\n\t\tdata-max-size=\"33554432\"\n\t\tdata-max-file-number=\"10\"\n\t\tdata-post-max-size=\"16777216\"\n\t\tdata-max-parallel-uploads=\"4\"\n\t\tdata-parallel-uploads=\"true\"\n\t\tdata-file-chunk-size=\"2097152\">\n\t<div class=\"dz-message\">\n\t\t<svg  viewBox=\"0 0 640 640\" focusable=\"false\" data-icon=\"inbox\" width=\"50px\" height=\"50px\" fill=\"currentColor\" aria-hidden=\"true\">\n\t\t\t<path d=\"M352 173.3L352 384C352 401.7 337.7 416 320 416C302.3 416 288 401.7 288 384L288 173.3L246.6 214.7C234.1 227.2 213.8 227.2 201.3 214.7C188.8 202.2 188.8 181.9 201.3 169.4L297.3 73.4C309.8 60.9 330.1 60.9 342.6 73.4L438.6 169.4C451.1 181.9 451.1 202.2 438.6 214.7C426.1 227.2 405.8 227.2 393.3 214.7L352 173.3zM320 464C364.2 464 400 428.2 400 384L480 384C515.3 384 544 412.7 544 448L544 480C544 515.3 515.3 544 480 544L160 544C124.7 544 96 515.3 96 480L96 448C96 412.7 124.7 384 160 384L240 384C240 428.2 275.8 464 320 464zM464 488C477.3 488 488 477.3 488 464C488 450.7 477.3 440 464 440C450.7 440 440 450.7 440 464C440 477.3 450.7 488 464 488z\"\/>\n\t\t<\/svg>\n\n\t\t<span class=\"modern-title\">\n\t\t\t\t\t\t\tDrag &amp; Drop Files, \t\t\t\t<span>Choose Files to Upload<\/span>\n\t\t\t\t\t<\/span>\n\n\t\t\t\t\t<span class=\"modern-hint\">Puedes subir hasta 10 archivos.<\/span>\n\t\t\t<\/div>\n<\/div>\n\n<input\n\t\ttype=\"text\"\n\t\tautocomplete=\"off\"\n\t\treadonly\n\t\tclass=\"dropzone-input\"\n\t\tstyle=\"position:absolute!important;clip:rect(0,0,0,0)!important;height:1px!important;width:1px!important;border:0!important;overflow:hidden!important;padding:0!important;margin:0!important;\"\n\t\tid=\"wpforms-91405-field_10\"\n\t\tname=\"wpforms_91405_10\" \t\tvalue=\"\">\n<div id=\"wpforms-91405-field_10-description\" class=\"wpforms-field-description\">Tipos de archivo aceptados: txt, rtf, odf, pdf, doc, docx, ppt, pptx, xls, xlsx, xml, zip, Tama\u00f1o m\u00e1ximo por archivo: 32\u00a0MB. N\u00famero m\u00e1ximo de archivos: 10.<\/div><\/div><\/div><\/div><\/div><\/div><div id=\"wpforms-91405-field_9-container\" class=\"wpforms-field wpforms-field-html\" data-field-id=\"9\"><div id=\"wpforms-91405-field_9\" aria-errormessage=\"wpforms-91405-field_9-error\"><font size=\"2\">Al hacer clic en \"Enviar\", acepta el <a href=\"\/wp-content\/uploads\/2021\/03\/processing-and-protection-of-personal-data-in-skrivanek-0.pdf\" title=\"tratamiento y la protecci\u00f3n de datos personales\" target=\"_blank\">tratamiento y la protecci\u00f3n de datos personales<\/a> por parte de Skrivanek.<\/font><\/div><\/div><div id=\"wpforms-91405-field_11-container\" class=\"wpforms-field wpforms-field-hidden\" data-field-id=\"11\"><input type=\"hidden\" id=\"wpforms-91405-field_11\" name=\"wpforms[fields][11]\" value=\"[channel]\"><\/div>\t\t<div id=\"wpforms-91405-field_4-container\"\n\t\t\tclass=\"wpforms-field wpforms-field-text\"\n\t\t\tdata-field-type=\"text\"\n\t\t\tdata-field-id=\"4\"\n\t\t\t>\n\t\t\t<label class=\"wpforms-field-label\" for=\"wpforms-91405-field_4\" >la Carga de<\/label>\n\t\t\t<input type=\"text\" id=\"wpforms-91405-field_4\" class=\"wpforms-field-medium\" name=\"wpforms[fields][4]\" >\n\t\t<\/div>\n\t\t<div id=\"wpforms-91405-field_12-container\" class=\"wpforms-field wpforms-field-hidden\" data-field-id=\"12\"><input type=\"hidden\" id=\"wpforms-91405-field_12\" name=\"wpforms[fields][12]\" value=\"[channeldrilldown1]\"><\/div><div id=\"wpforms-91405-field_13-container\" class=\"wpforms-field wpforms-field-hidden\" data-field-id=\"13\"><input type=\"hidden\" id=\"wpforms-91405-field_13\" name=\"wpforms[fields][13]\" value=\"[channeldrilldown2]\"><\/div><div id=\"wpforms-91405-field_14-container\" class=\"wpforms-field wpforms-field-hidden\" data-field-id=\"14\"><input type=\"hidden\" id=\"wpforms-91405-field_14\" name=\"wpforms[fields][14]\" value=\"[channeldrilldown3]\"><\/div><div id=\"wpforms-91405-field_15-container\" class=\"wpforms-field wpforms-field-hidden\" data-field-id=\"15\"><input type=\"hidden\" id=\"wpforms-91405-field_15\" name=\"wpforms[fields][15]\" value=\"[landingpage]\"><\/div><div id=\"wpforms-91405-field_16-container\" class=\"wpforms-field wpforms-field-hidden\" data-field-id=\"16\"><input type=\"hidden\" id=\"wpforms-91405-field_16\" name=\"wpforms[fields][16]\" value=\"[landingpagegroup]\"><\/div><script>\n\t\t\t\t( function() {\n\t\t\t\t\tconst style = document.createElement( 'style' );\n\t\t\t\t\tstyle.appendChild( document.createTextNode( '#wpforms-91405-field_4-container { position: absolute !important; overflow: hidden !important; display: inline !important; height: 1px !important; width: 1px !important; z-index: -1000 !important; padding: 0 !important; } #wpforms-91405-field_4-container input { visibility: hidden; } #wpforms-conversational-form-page #wpforms-91405-field_4-container label { counter-increment: none; }' ) );\n\t\t\t\t\tdocument.head.appendChild( style );\n\t\t\t\t\tdocument.currentScript?.remove();\n\t\t\t\t} )();\n\t\t\t<\/script><\/div><!-- .wpforms-field-container --><div class=\"wpforms-recaptcha-container wpforms-is-recaptcha wpforms-is-recaptcha-type-v3\" ><input type=\"hidden\" name=\"wpforms[recaptcha]\" value=\"\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"91405\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/skrivanek.com\/es\/wp-json\/wp\/v2\/pages\/7642\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-91405\" class=\"wpforms-submit\" data-alt-text=\"Enviando...\" data-submit-text=\"Enviar\" aria-live=\"assertive\" value=\"wpforms-submit\">Enviar<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/skrivanek.com\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Cargando\"><\/div><\/form><\/div>  <!-- .wpforms-container --><\/div><div id=\"panel-7642-1-1-1\" class=\"so-panel widget widget_wpa9-editor-ext panel-last-child\" data-index=\"4\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-wpa9-editor-ext so-widget-wpa9-editor-ext-default-c93e1481a745-7642\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h4><\/h4>\n<h4><a href=\"https:\/\/skrivanek.com\/wp-content\/uploads\/2024\/10\/lock.svg\"><img decoding=\"async\" class=\"alignnone wp-image-89553\" src=\"https:\/\/skrivanek.com\/wp-content\/uploads\/2024\/10\/lock.svg\" alt=\"data security\" width=\"30\" \/><\/a> Confidencialidad y seguridad de los datos<\/h4>\n<p>Priorizamos su privacidad y garantizamos que todos los servicios de interpretaci\u00f3n se gestionen con la m\u00e1xima confidencialidad. Nuestros procesos seguros aseguran que su informaci\u00f3n sensible est\u00e9 protegida en todo momento.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><div id=\"pg-7642-2\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-7642-2-0\"  class=\"panel-grid-cell\" ><div id=\"panel-7642-2-0-0\" class=\"so-panel widget widget_wpa9-carousel-images panel-first-child\" data-index=\"5\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-wpa9-carousel-images so-widget-wpa9-carousel-images-default-c93e1481a745-7642\"\n\t\t\t\n\t\t>\n<div class=\"wpa9-carousel-images\">\n\n\t<h3 class=\"widget-title\">Nuestros clientes satisfechos<\/h3>\n\t\n\t<div id=\"wpa9-carousel-images-DKBZhW\" class=\"carousel slide carousel-fade\" data-bs-interval=\"8000\" data-bs-ride=\"carousel\" data-bs-touch=\"true\">\n\n\t\t<div class=\"carousel-inner\">\n\n\t\t\t\n\t\t\t\n\t\t\t\t<div class=\"wpa9-carousel-images-item carousel-item bg-white active\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/skrivanek.com\/wp-content\/uploads\/2024\/06\/essox.svg\" alt=\"essox\" \/>\n\n\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/skrivanek.com\/wp-content\/uploads\/2024\/05\/ge-healthcare.svg\" alt=\"ge healthcare\" \/>\n\n\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/skrivanek.com\/wp-content\/uploads\/2024\/05\/honeywell.svg\" alt=\"honeywell\" \/>\n\n\t\t\t\t\t\t<br \/>\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\n\t\t<\/div>\n\t\t<!-- .carousel-inner -->\n\n\t\t\n\t<\/div>\n\t<!-- #wpa9-carousel-images -->\n\n<\/div>\n<!-- .wpa9-carousel-images -->\n<\/div><\/div><div id=\"panel-7642-2-0-1\" class=\"so-panel widget widget_wpa9-editor-ext panel-last-child\" data-index=\"6\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-wpa9-editor-ext so-widget-wpa9-editor-ext-default-c93e1481a745-7642\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h3 data-start=\"0\" data-end=\"30\"><strong data-start=\"0\" data-end=\"30\">\u00bfQu\u00e9 es la interpretaci\u00f3n?<\/strong><\/h3>\n<p data-start=\"32\" data-end=\"637\">La interpretaci\u00f3n es el proceso de convertir un idioma hablado o de signos desde una lengua de origen a una lengua de destino, permitiendo la comunicaci\u00f3n entre personas que no comparten un mismo idioma. A diferencia de la traducci\u00f3n, que se centra en textos escritos, la interpretaci\u00f3n se realiza en tiempo real y requiere un alto nivel de habilidad y concentraci\u00f3n. Los int\u00e9rpretes cualificados eliminan las barreras ling\u00fc\u00edsticas al escuchar al interlocutor, comprender el mensaje y transmitirlo con precisi\u00f3n en la lengua de destino, manteniendo el contexto, el tono y los matices del mensaje original.<\/p>\n<p data-start=\"639\" data-end=\"1025\" data-is-last-node=\"\" data-is-only-node=\"\">Nuestros servicios de interpretaci\u00f3n est\u00e1n dise\u00f1ados para facilitar una comunicaci\u00f3n fluida en diversos sectores y contextos, ya sea en reuniones de negocios, procedimientos legales, consultas m\u00e9dicas o conferencias internacionales. Con int\u00e9rpretes que trabajan en m\u00e1s de 110 idiomas, garantizamos que su mensaje sea comprendido de forma clara y precisa por todas las partes implicadas.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-7642-3\"  class=\"panel-grid panel-has-style\" ><div class=\"siteorigin-panels-stretch panel-row-padding-normal panel-row-style panel-row-style-for-7642-3\" data-stretch-type=\"full\" ><div id=\"pgc-7642-3-0\"  class=\"panel-grid-cell\" ><div id=\"panel-7642-3-0-0\" class=\"so-panel widget widget_wpa9-card-l panel-first-child\" data-index=\"7\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-wpa9-card-l so-widget-wpa9-card-l-default-c93e1481a745-7642\"\n\t\t\t\n\t\t>\n<h3 class=\"widget-title\">Tipos de servicios de interpretaci\u00f3n<\/h3>\n<div class=\"wpa9-card wpa9-card-l-container d-flex flex-wrap wpa9-columns-3\">\n\n\t\n\t\t\n\t<div class=\"wpa9-card-l-panel wpa9-panel shadow rounded d-flex flex-column justify-content-between\">\n\n\t\t<div>\n\t\t\t\t\t\t\t<span class=\"wpa9-panel-icon icon\" style=\"display: none; background-image: url('https:\/\/skrivanek.com\/wp-content\/uploads\/2021\/03\/ico-tlumoceni-simultanni.svg')\"><\/span>\n\t\t\t<span class=\"wpa9-panel-icon icon\" style=\"mask-image: url(https:\/\/skrivanek.com\/wp-content\/uploads\/2021\/03\/ico-tlumoceni-simultanni.svg); -webkit-mask-image: url(https:\/\/skrivanek.com\/wp-content\/uploads\/2021\/03\/ico-tlumoceni-simultanni.svg);\"><\/span>\n\t\t\n\t\t\t\t\t\t\t\t<h2 class=\"wpa9-panel-title\">Interpretaci\u00f3n simult\u00e1nea<\/h2>\n\t\t\n\t\t\t\t\t\t\t<div class=\"wpa9-panel-content\"><p>En la interpretaci\u00f3n simult\u00e1nea, el int\u00e9rprete escucha al orador en el idioma de origen y transmite el mensaje de forma simult\u00e1nea en el idioma de destino. Este m\u00e9todo se utiliza habitualmente en conferencias, seminarios y eventos de gran escala, donde la comunicaci\u00f3n en tiempo real es esencial. Los int\u00e9rpretes que trabajan en esta modalidad necesitan excelentes habilidades de multitarea y un profundo conocimiento de la materia para garantizar la m\u00e1xima precisi\u00f3n.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\n\t\t\n\t<\/div>\n\n\t\t\n\t<div class=\"wpa9-card-l-panel wpa9-panel shadow rounded d-flex flex-column justify-content-between\">\n\n\t\t<div>\n\t\t\t\t\t\t\t<span class=\"wpa9-panel-icon icon\" style=\"display: none; background-image: url('https:\/\/skrivanek.com\/wp-content\/uploads\/2021\/03\/ico-tlumoceni-konsekutivni.svg')\"><\/span>\n\t\t\t<span class=\"wpa9-panel-icon icon\" style=\"mask-image: url(https:\/\/skrivanek.com\/wp-content\/uploads\/2021\/03\/ico-tlumoceni-konsekutivni.svg); -webkit-mask-image: url(https:\/\/skrivanek.com\/wp-content\/uploads\/2021\/03\/ico-tlumoceni-konsekutivni.svg);\"><\/span>\n\t\t\n\t\t\t\t\t\t\t\t<h2 class=\"wpa9-panel-title\">Interpretaci\u00f3n consecutiva<\/h2>\n\t\t\n\t\t\t\t\t\t\t<div class=\"wpa9-panel-content\"><p>La interpretaci\u00f3n consecutiva consiste en que el int\u00e9rprete escucha un fragmento del discurso en el idioma de origen y, tras una pausa del orador, lo transmite en el idioma de destino. Se utiliza normalmente en entornos m\u00e1s reducidos, como reuniones, entrevistas o audiencias judiciales. La pausa entre intervenciones permite al int\u00e9rprete transmitir el mensaje con precisi\u00f3n y claridad.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\n\t\t\n\t<\/div>\n\n\t\t\n\t<div class=\"wpa9-card-l-panel wpa9-panel shadow rounded d-flex flex-column justify-content-between\">\n\n\t\t<div>\n\t\t\t\t\t\t\t<span class=\"wpa9-panel-icon icon\" style=\"display: none; background-image: url('https:\/\/skrivanek.com\/wp-content\/uploads\/2021\/03\/ico-tlumoceni-online.svg')\"><\/span>\n\t\t\t<span class=\"wpa9-panel-icon icon\" style=\"mask-image: url(https:\/\/skrivanek.com\/wp-content\/uploads\/2021\/03\/ico-tlumoceni-online.svg); -webkit-mask-image: url(https:\/\/skrivanek.com\/wp-content\/uploads\/2021\/03\/ico-tlumoceni-online.svg);\"><\/span>\n\t\t\n\t\t\t\t\t\t\t\t<h2 class=\"wpa9-panel-title\">Interpretaci\u00f3n remota por tel\u00e9fono y videollamada<\/h2>\n\t\t\n\t\t\t\t\t\t\t<div class=\"wpa9-panel-content\"><p>Con el creciente auge de la comunicaci\u00f3n a distancia, la interpretaci\u00f3n remota por tel\u00e9fono y videollamada se ha vuelto esencial. Nuestros servicios incluyen estas soluciones flexibles, en las que int\u00e9rpretes cualificados trabajan de forma remota para ofrecer asistencia ling\u00fc\u00edstica en tiempo real, garantizando una comunicaci\u00f3n fluida m\u00e1s all\u00e1 de fronteras y zonas horarias.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\n\t\t\n\t<\/div>\n\n\t\t\n\t\n<\/div>\n<\/div><\/div><div id=\"panel-7642-3-0-1\" class=\"so-panel widget widget_wpa9-card-l\" data-index=\"8\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-wpa9-card-l so-widget-wpa9-card-l-default-c93e1481a745-7642\"\n\t\t\t\n\t\t>\n<h3 class=\"widget-title\">Servicios de interpretaci\u00f3n especializada<\/h3>\n<div class=\"wpa9-card wpa9-card-l-container d-flex flex-wrap wpa9-columns-3\">\n\n\t\n\t\t\n\t<div class=\"wpa9-card-l-panel wpa9-panel shadow rounded d-flex flex-column justify-content-between\">\n\n\t\t<div>\n\t\t\t\t\t\t\t<span class=\"wpa9-panel-icon icon\" style=\"display: none; background-image: url('https:\/\/skrivanek.com\/wp-content\/uploads\/2021\/03\/ico-medicinsky-preklad.svg')\"><\/span>\n\t\t\t<span class=\"wpa9-panel-icon icon\" style=\"mask-image: url(https:\/\/skrivanek.com\/wp-content\/uploads\/2021\/03\/ico-medicinsky-preklad.svg); -webkit-mask-image: url(https:\/\/skrivanek.com\/wp-content\/uploads\/2021\/03\/ico-medicinsky-preklad.svg);\"><\/span>\n\t\t\n\t\t\t\t\t\t\t\t<h2 class=\"wpa9-panel-title\">Interpretaci\u00f3n m\u00e9dica<\/h2>\n\t\t\n\t\t\t\t\t\t\t<div class=\"wpa9-panel-content\"><p>La interpretaci\u00f3n m\u00e9dica es fundamental en el \u00e1mbito sanitario, donde una comunicaci\u00f3n clara y precisa puede ser cuesti\u00f3n de vida o muerte. Nuestros int\u00e9rpretes cualificados colaboran con profesionales de la salud para garantizar que los pacientes que hablan distintos idiomas comprendan su diagn\u00f3stico, las opciones de tratamiento y los planes de atenci\u00f3n. Est\u00e1n familiarizados con la terminolog\u00eda m\u00e9dica tanto en el idioma de origen como en el de destino, ofreciendo interpretaciones precisas y culturalmente adecuadas.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\n\t\t\n\t<\/div>\n\n\t\t\n\t<div class=\"wpa9-card-l-panel wpa9-panel shadow rounded d-flex flex-column justify-content-between\">\n\n\t\t<div>\n\t\t\t\t\t\t\t<span class=\"wpa9-panel-icon icon\" style=\"display: none; background-image: url('https:\/\/skrivanek.com\/wp-content\/uploads\/2024\/10\/law.svg')\"><\/span>\n\t\t\t<span class=\"wpa9-panel-icon icon\" style=\"mask-image: url(https:\/\/skrivanek.com\/wp-content\/uploads\/2024\/10\/law.svg); -webkit-mask-image: url(https:\/\/skrivanek.com\/wp-content\/uploads\/2024\/10\/law.svg);\"><\/span>\n\t\t\n\t\t\t\t\t\t\t\t<h2 class=\"wpa9-panel-title\">Interpretaci\u00f3n jur\u00eddica<\/h2>\n\t\t\n\t\t\t\t\t\t\t<div class=\"wpa9-panel-content\"><p>La interpretaci\u00f3n jur\u00eddica requiere un profundo conocimiento de la terminolog\u00eda y los procedimientos legales. Ya sea en audiencias judiciales, declaraciones o consultas legales, nuestros int\u00e9rpretes garantizan que todas las partes comprendan plenamente los procedimientos, independientemente de su idioma. La precisi\u00f3n es esencial en este \u00e1mbito, y nuestro equipo cuenta con la experiencia necesaria para manejar un lenguaje legal complejo, manteniendo la confidencialidad y la imparcialidad.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\n\t\t\n\t<\/div>\n\n\t\t\n\t<div class=\"wpa9-card-l-panel wpa9-panel shadow rounded d-flex flex-column justify-content-between\">\n\n\t\t<div>\n\t\t\t\t\t\t\t<span class=\"wpa9-panel-icon icon\" style=\"display: none; background-image: url('https:\/\/skrivanek.com\/wp-content\/uploads\/2024\/06\/robotizace.svg')\"><\/span>\n\t\t\t<span class=\"wpa9-panel-icon icon\" style=\"mask-image: url(https:\/\/skrivanek.com\/wp-content\/uploads\/2024\/06\/robotizace.svg); -webkit-mask-image: url(https:\/\/skrivanek.com\/wp-content\/uploads\/2024\/06\/robotizace.svg);\"><\/span>\n\t\t\n\t\t\t\t\t\t\t\t<h2 class=\"wpa9-panel-title\">Interpretaci\u00f3n t\u00e9cnica<\/h2>\n\t\t\n\t\t\t\t\t\t\t<div class=\"wpa9-panel-content\"><p>En sectores altamente t\u00e9cnicos, como la ingenier\u00eda, la inform\u00e1tica o la industria manufacturera, la interpretaci\u00f3n requiere no solo competencias ling\u00fc\u00edsticas, sino tambi\u00e9n un s\u00f3lido dominio de la terminolog\u00eda t\u00e9cnica. Nuestros int\u00e9rpretes especializados conocen a fondo estos sectores, asegurando que conceptos complejos y t\u00e9rminos especializados se transmitan con exactitud tanto en el idioma de origen como en el de destino.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\n\t\t\n\t<\/div>\n\n\t\t\n\t<div class=\"wpa9-card-l-panel wpa9-panel shadow rounded d-flex flex-column justify-content-between\">\n\n\t\t<div>\n\t\t\t\t\t\t\t<span class=\"wpa9-panel-icon icon\" style=\"display: none; background-image: url('https:\/\/skrivanek.com\/wp-content\/uploads\/2024\/06\/finance.svg')\"><\/span>\n\t\t\t<span class=\"wpa9-panel-icon icon\" style=\"mask-image: url(https:\/\/skrivanek.com\/wp-content\/uploads\/2024\/06\/finance.svg); -webkit-mask-image: url(https:\/\/skrivanek.com\/wp-content\/uploads\/2024\/06\/finance.svg);\"><\/span>\n\t\t\n\t\t\t\t\t\t\t\t<h2 class=\"wpa9-panel-title\">Interpretaci\u00f3n financiera y econ\u00f3mica<\/h2>\n\t\t\n\t\t\t\t\t\t\t<div class=\"wpa9-panel-content\"><p>En negociaciones financieras, debates econ\u00f3micos o reuniones corporativas, la comunicaci\u00f3n precisa es clave. Nuestros int\u00e9rpretes especializados en econom\u00eda y finanzas cuentan con la experiencia necesaria para manejar terminolog\u00eda financiera compleja, garantizando una comunicaci\u00f3n fluida en contextos empresariales cr\u00edticos.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\n\t\t\n\t<\/div>\n\n\t\t\n\t<div class=\"wpa9-card-l-panel wpa9-panel shadow rounded d-flex flex-column justify-content-between\">\n\n\t\t<div>\n\t\t\t\t\t\t\t<span class=\"wpa9-panel-icon icon\" style=\"display: none; background-image: url('https:\/\/skrivanek.com\/wp-content\/uploads\/2021\/03\/ico-certifikovana-spolecnost.svg')\"><\/span>\n\t\t\t<span class=\"wpa9-panel-icon icon\" style=\"mask-image: url(https:\/\/skrivanek.com\/wp-content\/uploads\/2021\/03\/ico-certifikovana-spolecnost.svg); -webkit-mask-image: url(https:\/\/skrivanek.com\/wp-content\/uploads\/2021\/03\/ico-certifikovana-spolecnost.svg);\"><\/span>\n\t\t\n\t\t\t\t\t\t\t\t<h2 class=\"wpa9-panel-title\">Interpretaci\u00f3n gubernamental y diplom\u00e1tica<\/h2>\n\t\t\n\t\t\t\t\t\t\t<div class=\"wpa9-panel-content\"><p>Nuestros int\u00e9rpretes tambi\u00e9n trabajan en entornos gubernamentales, facilitando la comunicaci\u00f3n entre funcionarios, diplom\u00e1ticos y organizaciones internacionales. Ya se trate de debates pol\u00edticos de alto nivel o de interacciones en el \u00e1mbito p\u00fablico, nuestro equipo asegura que todas las partes se comuniquen de forma clara y eficaz.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\n\t\t\n\t<\/div>\n\n\t\t\n\t<div class=\"wpa9-card-l-panel wpa9-panel shadow rounded d-flex flex-column justify-content-between\">\n\n\t\t<div>\n\t\t\t\t\t\t\t<span class=\"wpa9-panel-icon icon\" style=\"display: none; background-image: url('https:\/\/skrivanek.com\/wp-content\/uploads\/2024\/10\/chemie-technologie.svg')\"><\/span>\n\t\t\t<span class=\"wpa9-panel-icon icon\" style=\"mask-image: url(https:\/\/skrivanek.com\/wp-content\/uploads\/2024\/10\/chemie-technologie.svg); -webkit-mask-image: url(https:\/\/skrivanek.com\/wp-content\/uploads\/2024\/10\/chemie-technologie.svg);\"><\/span>\n\t\t\n\t\t\t\t\t\t\t\t<h2 class=\"wpa9-panel-title\">Interpretaci\u00f3n cient\u00edfica<\/h2>\n\t\t\n\t\t\t\t\t\t\t<div class=\"wpa9-panel-content\"><p>En conferencias cient\u00edficas, presentaciones de investigaci\u00f3n y debates acad\u00e9micos, una interpretaci\u00f3n precisa es esencial para garantizar que conceptos cient\u00edficos complejos se comuniquen con claridad. Nuestros int\u00e9rpretes cient\u00edficos cuentan con la experiencia necesaria para manejar terminolog\u00eda especializada en \u00e1reas como la biolog\u00eda, la qu\u00edmica, la f\u00edsica y otras disciplinas, facilitando una comunicaci\u00f3n fluida entre investigadores y expertos de distintos contextos ling\u00fc\u00edsticos.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\n\t\t\n\t<\/div>\n\n\t\t\n\t\n<\/div>\n<\/div><\/div><div id=\"panel-7642-3-0-2\" class=\"so-panel widget widget_wpa9-editor-ext\" data-index=\"9\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-wpa9-editor-ext so-widget-wpa9-editor-ext-default-c93e1481a745-7642\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h3 style=\"text-align: center;\" data-start=\"0\" data-end=\"45\"><strong data-start=\"0\" data-end=\"45\">\u00bfPor qu\u00e9 es importante la interpretaci\u00f3n?<\/strong><\/h3>\n<p style=\"text-align: center;\" data-start=\"47\" data-end=\"487\">La interpretaci\u00f3n desempe\u00f1a un papel fundamental en la eliminaci\u00f3n de las barreras ling\u00fc\u00edsticas y en la facilitaci\u00f3n de una comunicaci\u00f3n clara entre diferentes culturas e idiomas. En el mundo globalizado actual, donde empresas, gobiernos e individuos interact\u00faan a escala internacional, la capacidad de comunicarse con precisi\u00f3n y en tiempo real es esencial. Estas son algunas de las razones por las que la interpretaci\u00f3n es tan importante:<\/p>\n<p data-start=\"47\" data-end=\"487\">\n<\/p><\/div>\n<\/div><\/div><div id=\"panel-7642-3-0-3\" class=\"so-panel widget widget_wpa9-card-l panel-last-child\" data-index=\"10\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-wpa9-card-l so-widget-wpa9-card-l-default-c93e1481a745-7642\"\n\t\t\t\n\t\t>\n\n<div class=\"wpa9-card wpa9-card-l-container d-flex flex-wrap wpa9-columns-3\">\n\n\t\n\t\t\n\t<div class=\"wpa9-card-l-panel wpa9-panel shadow rounded d-flex flex-column justify-content-between\">\n\n\t\t<div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t<h2 class=\"wpa9-panel-title\">Facilita los negocios internacionales<\/h2>\n\t\t\n\t\t\t\t\t\t\t<div class=\"wpa9-panel-content\"><p>En entornos empresariales internacionales, una comunicaci\u00f3n eficaz es clave para establecer relaciones, cerrar acuerdos y gestionar negociaciones complejas. Los int\u00e9rpretes cualificados garantizan que todas las partes comprendan plenamente los t\u00e9rminos, las condiciones y los matices, reduciendo el riesgo de malentendidos y fomentando relaciones comerciales exitosas.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\n\t\t\n\t<\/div>\n\n\t\t\n\t<div class=\"wpa9-card-l-panel wpa9-panel shadow rounded d-flex flex-column justify-content-between\">\n\n\t\t<div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t<h2 class=\"wpa9-panel-title\">Garantiza el acceso a servicios esenciales<\/h2>\n\t\t\n\t\t\t\t\t\t\t<div class=\"wpa9-panel-content\"><p>En sectores cr\u00edticos como la sanidad, el \u00e1mbito legal y los servicios p\u00fablicos, la interpretaci\u00f3n asegura que todas las personas, independientemente de su nivel de dominio del idioma, tengan acceso a la informaci\u00f3n que necesitan. Los servicios de interpretaci\u00f3n permiten a los pacientes comunicarse con profesionales sanitarios, garantizan un trato justo en procedimientos legales y facilitan el acceso a servicios gubernamentales, promoviendo la equidad y la inclusi\u00f3n en la sociedad.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\n\t\t\n\t<\/div>\n\n\t\t\n\t<div class=\"wpa9-card-l-panel wpa9-panel shadow rounded d-flex flex-column justify-content-between\">\n\n\t\t<div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t<h2 class=\"wpa9-panel-title\">Refuerza las relaciones diplom\u00e1ticas e internacionales<\/h2>\n\t\t\n\t\t\t\t\t\t\t<div class=\"wpa9-panel-content\"><p>Para gobiernos, ONG y organizaciones internacionales, la interpretaci\u00f3n es clave para mantener relaciones diplom\u00e1ticas, llevar a cabo negociaciones y participar en foros globales. Los int\u00e9rpretes que trabajan en estos contextos ayudan a transmitir los mensajes con precisi\u00f3n y sensibilidad diplom\u00e1tica, asegurando que los matices culturales y los temas delicados se gestionen adecuadamente.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\n\t\t\n\t<\/div>\n\n\t\t\n\t<div class=\"wpa9-card-l-panel wpa9-panel shadow rounded d-flex flex-column justify-content-between\">\n\n\t\t<div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t<h2 class=\"wpa9-panel-title\">Apoyo a eventos y conferencias multiling\u00fces<\/h2>\n\t\t\n\t\t\t\t\t\t\t<div class=\"wpa9-panel-content\"><p>Las conferencias, seminarios y reuniones internacionales suelen reunir a participantes de distintos contextos ling\u00fc\u00edsticos. La interpretaci\u00f3n profesional permite que todos los asistentes participen activamente en los debates, independientemente de su idioma materno. Esto fomenta un entorno m\u00e1s inclusivo y garantiza que la informaci\u00f3n importante se transmita de forma precisa y coherente.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\n\t\t\n\t<\/div>\n\n\t\t\n\t<div class=\"wpa9-card-l-panel wpa9-panel shadow rounded d-flex flex-column justify-content-between\">\n\n\t\t<div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t<h2 class=\"wpa9-panel-title\">Superaci\u00f3n de barreras culturales<\/h2>\n\t\t\n\t\t\t\t\t\t\t<div class=\"wpa9-panel-content\"><p>Una interpretaci\u00f3n eficaz va m\u00e1s all\u00e1 de traducir palabras: capta el contexto cultural, el tono y el significado del mensaje. De este modo, los int\u00e9rpretes contribuyen a superar las barreras culturales, fomentando la comprensi\u00f3n mutua y el respeto entre personas de diferentes or\u00edgenes.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\n\t\t\n\t<\/div>\n\n\t\t\n\t<div class=\"wpa9-card-l-panel wpa9-panel shadow rounded d-flex flex-column justify-content-between\">\n\n\t\t<div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t<h2 class=\"wpa9-panel-title\">Protecci\u00f3n de los derechos legales<\/h2>\n\t\t\n\t\t\t\t\t\t\t<div class=\"wpa9-panel-content\"><p>En el \u00e1mbito jur\u00eddico, la importancia de la interpretaci\u00f3n es fundamental. La interpretaci\u00f3n legal garantiza que las personas que no dominan el idioma comprendan plenamente sus derechos, los procedimientos y las posibles consecuencias legales. Esto es clave para asegurar resultados justos y equitativos, as\u00ed como para defender el principio de igualdad en el acceso a la justicia.<\/p>\n<\/div>\n\t\t\t\t<\/div>\n\n\t\t\n\t<\/div>\n\n\t\t\n\t\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><div id=\"pg-7642-4\"  class=\"panel-grid panel-has-style\" ><div class=\"siteorigin-panels-stretch panel-row-padding-normal panel-row-style panel-row-style-for-7642-4\" data-stretch-type=\"full\" ><div id=\"pgc-7642-4-0\"  class=\"panel-grid-cell\" ><div id=\"panel-7642-4-0-0\" class=\"so-panel widget widget_wpa9-editor-ext panel-first-child panel-last-child\" data-index=\"11\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-wpa9-editor-ext so-widget-wpa9-editor-ext-default-c93e1481a745-7642\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h3 style=\"text-align: center;\">Conozca por adelantado el precio de los servicios de interpretaci\u00f3n.<\/h3>\n<p>\u00a0<\/p>\n<p style=\"text-align: left;\">Proporci\u00f3nenos todos los detalles del evento, si es en persona o en remoto, y elaboraremos un presupuesto detallado y preciso antes de iniciar el proyecto. Puede confiar en nuestra experiencia a la hora de recomendarle qu\u00e9 tipo de interpretaci\u00f3n elegir.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><div id=\"pg-7642-5\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-7642-5-0\"  class=\"panel-grid-cell\" ><div id=\"panel-7642-5-0-0\" class=\"so-panel widget widget_wpa9-steps panel-first-child panel-last-child\" data-index=\"12\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-wpa9-steps so-widget-wpa9-steps-default-c93e1481a745-7642\"\n\t\t\t\n\t\t><h3 class=\"widget-title\">El proceso de interpretaci\u00f3n<\/h3><div class=\"wpa9-steps\">\n\t<div class=\"wpa9-steps-togglers d-flex flex-wrap justify-content-center\" data-wpa9-interval=\"7000\">\n\t\t\t\n\t\t<div class=\"wpa9-steps-toggler-wrapper wpa9-steps-active\" id=\"wpa9-steps-toggler-panel-0\">\n\t\t\t<div class=\"wpa9-steps-toggler f-headlines d-flex align-items-center justify-content-center\" data-content=\"panel-0\" role=\"button\">\n\t\t\t\t\t\t\t\t<span class=\"wpa9-step-title\">Colaboramos con usted<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"wpa9-steps-decoration\"><\/div>\n\t\t<\/div>\n\t\t<div class=\"wpa9-steps-content wpa9-steps-active\" role=\"region\" id=\"wpa9-steps-content-panel-0\">\n\t\t\t<p>D\u00edganos para qu\u00e9 tipo de evento necesita la interpretaci\u00f3n y le recomendaremos el tipo de interpretaci\u00f3n que m\u00e1s se ajuste a sus necesidades. O simplemente d\u00edganos lo que prefiere y elaboraremos un\u00a0presupuesto.<\/p>\n\t\t<\/div>\n\t\t<div class=\"wpa9-steps-hyphen hyphen-visible\"><\/div>\t\t\t\n\t\t<div class=\"wpa9-steps-toggler-wrapper\" id=\"wpa9-steps-toggler-panel-1\">\n\t\t\t<div class=\"wpa9-steps-toggler f-headlines d-flex align-items-center justify-content-center\" data-content=\"panel-1\" role=\"button\">\n\t\t\t\t\t\t\t\t<span class=\"wpa9-step-title\">Le presentamos a su int\u00e9rprete<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"wpa9-steps-decoration\"><\/div>\n\t\t<\/div>\n\t\t<div class=\"wpa9-steps-content\" role=\"region\" id=\"wpa9-steps-content-panel-1\">\n\t\t\t<p>Cuando haya aprobado el presupuesto, le pondremos en contacto directamente con el int\u00e9rprete asignado. H\u00e1blele de sus planes.<\/p>\n\t\t<\/div>\n\t\t<div class=\"wpa9-steps-hyphen hyphen-visible\"><\/div>\t\t\t\n\t\t<div class=\"wpa9-steps-toggler-wrapper\" id=\"wpa9-steps-toggler-panel-2\">\n\t\t\t<div class=\"wpa9-steps-toggler f-headlines d-flex align-items-center justify-content-center\" data-content=\"panel-2\" role=\"button\">\n\t\t\t\t\t\t\t\t<span class=\"wpa9-step-title\">Ofrecemos flexibilidad<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"wpa9-steps-decoration\"><\/div>\n\t\t<\/div>\n\t\t<div class=\"wpa9-steps-content\" role=\"region\" id=\"wpa9-steps-content-panel-2\">\n\t\t\t<p>Nuestros int\u00e9rpretes afables y serviciales estar\u00e1n disponibles para usted en cualquier momento durante el evento. Si no est\u00e1 seguro del proceso o tiene alguna pregunta, no dude en recurrir a su int\u00e9rprete.<\/p>\n\t\t<\/div>\n\t\t<div class=\"wpa9-steps-hyphen hyphen-visible\"><\/div>\t\t\t\n\t\t<div class=\"wpa9-steps-toggler-wrapper\" id=\"wpa9-steps-toggler-panel-3\">\n\t\t\t<div class=\"wpa9-steps-toggler f-headlines d-flex align-items-center justify-content-center\" data-content=\"panel-3\" role=\"button\">\n\t\t\t\t\t\t\t\t<span class=\"wpa9-step-title\">Facilitamos los futuros proyectos<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"wpa9-steps-decoration\"><\/div>\n\t\t<\/div>\n\t\t<div class=\"wpa9-steps-content\" role=\"region\" id=\"wpa9-steps-content-panel-3\">\n\t\t\t<p>\u00bfEst\u00e1 satisfecho con el int\u00e9rprete?. Puede realizar una petici\u00f3n especial para que el mismo int\u00e9rprete le acompa\u00f1e en su pr\u00f3ximo evento. Estaremos encantados de asign\u00e1rselo.<\/p>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t<div class=\"wpa9-steps-contents-wrapper\">\n\t\t\t\t\t<div class=\"wpa9-steps-content _step_4_1 wpa9-steps-active\" role=\"region\" id=\"wpa9-steps-content-panel-0\">\n\t\t\t<p>D\u00edganos para qu\u00e9 tipo de evento necesita la interpretaci\u00f3n y le recomendaremos el tipo de interpretaci\u00f3n que m\u00e1s se ajuste a sus necesidades. O simplemente d\u00edganos lo que prefiere y elaboraremos un\u00a0presupuesto.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"wpa9-steps-content _step_4_2\" role=\"region\" id=\"wpa9-steps-content-panel-1\">\n\t\t\t<p>Cuando haya aprobado el presupuesto, le pondremos en contacto directamente con el int\u00e9rprete asignado. H\u00e1blele de sus planes.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"wpa9-steps-content _step_4_3\" role=\"region\" id=\"wpa9-steps-content-panel-2\">\n\t\t\t<p>Nuestros int\u00e9rpretes afables y serviciales estar\u00e1n disponibles para usted en cualquier momento durante el evento. Si no est\u00e1 seguro del proceso o tiene alguna pregunta, no dude en recurrir a su int\u00e9rprete.<\/p>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"wpa9-steps-content _step_4_4\" role=\"region\" id=\"wpa9-steps-content-panel-3\">\n\t\t\t<p>\u00bfEst\u00e1 satisfecho con el int\u00e9rprete?. Puede realizar una petici\u00f3n especial para que el mismo int\u00e9rprete le acompa\u00f1e en su pr\u00f3ximo evento. Estaremos encantados de asign\u00e1rselo.<\/p>\n\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-7642-6\"  class=\"panel-grid panel-has-style\" ><div class=\"siteorigin-panels-stretch panel-row-padding-none panel-row-style panel-row-style-for-7642-6\" data-stretch-type=\"full\" ><div id=\"pgc-7642-6-0\"  class=\"panel-grid-cell\" ><div id=\"panel-7642-6-0-0\" class=\"so-panel widget widget_wpa9-accordion panel-first-child panel-last-child\" data-index=\"13\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-wpa9-accordion so-widget-wpa9-accordion-default-c93e1481a745-7642\"\n\t\t\t\n\t\t><h3 class=\"widget-title\">Preguntas frecuentes<\/h3><div class=\"wpa9-accordion\">\n\t<div class=\"wpa9-accordion-panel\" id=\"wpa9-accordion-panel-cual-es-el-proposito-de-la-interpretacion\">\n\n\t\t<div class=\"wpa9-accordion-toggler d-flex\" data-panel=\"cual-es-el-proposito-de-la-interpretacion\" role=\"button\" aria-controls=\"wpa9-accordion-panel-cual-es-el-proposito-de-la-interpretacion\" aria-expanded=\"false\">\n\n\t\t\t<div class=\"wpa9-accordion-icon wpa9-accordion-icon-open\"><\/div>\n\n\t\t\t<div class=\"wpa9-accordion-title\">\u00bfCu\u00e1l es el prop\u00f3sito de la interpretaci\u00f3n?<\/div>\n\n\t\t<\/div>\n\n\t\t<div class=\"wpa9-accordion-content\" role=\"region\">\n\t\t\tEl prop\u00f3sito de la interpretaci\u00f3n es permitir una comunicaci\u00f3n precisa, ya sea presencial, en l\u00ednea o por tel\u00e9fono, entre personas o grupos que hablan distintos idiomas. Esto se logra mediante la traducci\u00f3n oral realizada por int\u00e9rpretes cualificados.\t\t<\/div>\n\n\t<\/div>\n\t<div class=\"wpa9-accordion-panel\" id=\"wpa9-accordion-panel-que-tipo-de-interpretacion-ofrece-skrivanek\">\n\n\t\t<div class=\"wpa9-accordion-toggler d-flex\" data-panel=\"que-tipo-de-interpretacion-ofrece-skrivanek\" role=\"button\" aria-controls=\"wpa9-accordion-panel-que-tipo-de-interpretacion-ofrece-skrivanek\" aria-expanded=\"false\">\n\n\t\t\t<div class=\"wpa9-accordion-icon wpa9-accordion-icon-open\"><\/div>\n\n\t\t\t<div class=\"wpa9-accordion-title\">\u00bfQu\u00e9 tipo de interpretaci\u00f3n ofrece Skrivanek?<\/div>\n\n\t\t<\/div>\n\n\t\t<div class=\"wpa9-accordion-content\" role=\"region\">\n\t\t\tInterpretaci\u00f3n en juzgados, de conferencias y reuniones o interpretaci\u00f3n remota. Nuestro equipo cualificado puede trabajar en combinaciones de hasta 80 idiomas.\t\t<\/div>\n\n\t<\/div>\n\t<div class=\"wpa9-accordion-panel\" id=\"wpa9-accordion-panel-puedo-trabajar-con-el-mismo-interprete-para-mi-proximo-evento\">\n\n\t\t<div class=\"wpa9-accordion-toggler d-flex\" data-panel=\"puedo-trabajar-con-el-mismo-interprete-para-mi-proximo-evento\" role=\"button\" aria-controls=\"wpa9-accordion-panel-puedo-trabajar-con-el-mismo-interprete-para-mi-proximo-evento\" aria-expanded=\"false\">\n\n\t\t\t<div class=\"wpa9-accordion-icon wpa9-accordion-icon-open\"><\/div>\n\n\t\t\t<div class=\"wpa9-accordion-title\">\u00bfPuedo trabajar con el mismo int\u00e9rprete para mi pr\u00f3ximo evento?<\/div>\n\n\t\t<\/div>\n\n\t\t<div class=\"wpa9-accordion-content\" role=\"region\">\n\t\t\tS\u00ed, si est\u00e1 satisfecho con el trabajo de un int\u00e9rprete concreto que est\u00e9 disponible para su pr\u00f3ximo evento, estaremos encantados de asign\u00e1rselo de nuevo.\t\t<\/div>\n\n\t<\/div>\n\t<div class=\"wpa9-accordion-panel\" id=\"wpa9-accordion-panel-cuanto-tiempo-pasara-el-interprete-conmigo\">\n\n\t\t<div class=\"wpa9-accordion-toggler d-flex\" data-panel=\"cuanto-tiempo-pasara-el-interprete-conmigo\" role=\"button\" aria-controls=\"wpa9-accordion-panel-cuanto-tiempo-pasara-el-interprete-conmigo\" aria-expanded=\"false\">\n\n\t\t\t<div class=\"wpa9-accordion-icon wpa9-accordion-icon-open\"><\/div>\n\n\t\t\t<div class=\"wpa9-accordion-title\">\u00bfCu\u00e1nto tiempo pasar\u00e1 el int\u00e9rprete conmigo?<\/div>\n\n\t\t<\/div>\n\n\t\t<div class=\"wpa9-accordion-content\" role=\"region\">\n\t\t\tEsto depende del acuerdo concreto al que hayamos llegado y de cu\u00e1les sean los requisitos. Si cree que necesita un int\u00e9rprete para un tiempo espec\u00edfico, nos aseguraremos de que est\u00e9 100\u00a0% disponible.\t\t<\/div>\n\n\t<\/div>\n\t<div class=\"wpa9-accordion-panel\" id=\"wpa9-accordion-panel-cual-es-el-coste-de-la-interpretacion-y-cuanto-debo-pagar-por-adelantado\">\n\n\t\t<div class=\"wpa9-accordion-toggler d-flex\" data-panel=\"cual-es-el-coste-de-la-interpretacion-y-cuanto-debo-pagar-por-adelantado\" role=\"button\" aria-controls=\"wpa9-accordion-panel-cual-es-el-coste-de-la-interpretacion-y-cuanto-debo-pagar-por-adelantado\" aria-expanded=\"false\">\n\n\t\t\t<div class=\"wpa9-accordion-icon wpa9-accordion-icon-open\"><\/div>\n\n\t\t\t<div class=\"wpa9-accordion-title\">\u00bfCu\u00e1l es el coste de la interpretaci\u00f3n y cu\u00e1nto debo pagar por adelantado?<\/div>\n\n\t\t<\/div>\n\n\t\t<div class=\"wpa9-accordion-content\" role=\"region\">\n\t\t\tFacil\u00edtenos todos los detalles de su evento, ya sea presencial o remoto, y le proporcionaremos un presupuesto detallado y preciso antes de iniciar el proyecto. No se preocupe si no tiene claro qu\u00e9 necesita: puede confiar en nuestra experiencia para recomendarle el tipo de interpretaci\u00f3n m\u00e1s adecuado.\n\nPara nuevos clientes, solicitamos un anticipo del 50 % para los servicios de interpretaci\u00f3n, y el resto se abona al finalizar el proyecto. En el caso de clientes habituales, no es necesario realizar ning\u00fan anticipo.\t\t<\/div>\n\n\t<\/div>\n\t<div class=\"wpa9-accordion-panel\" id=\"wpa9-accordion-panel-se-aplica-algun-cargo-por-la-cancelacion-de-un-servicio-de-interpretacion\">\n\n\t\t<div class=\"wpa9-accordion-toggler d-flex\" data-panel=\"se-aplica-algun-cargo-por-la-cancelacion-de-un-servicio-de-interpretacion\" role=\"button\" aria-controls=\"wpa9-accordion-panel-se-aplica-algun-cargo-por-la-cancelacion-de-un-servicio-de-interpretacion\" aria-expanded=\"false\">\n\n\t\t\t<div class=\"wpa9-accordion-icon wpa9-accordion-icon-open\"><\/div>\n\n\t\t\t<div class=\"wpa9-accordion-title\">\u00bfSe aplica alg\u00fan cargo por la cancelaci\u00f3n de un servicio de interpretaci\u00f3n?<\/div>\n\n\t\t<\/div>\n\n\t\t<div class=\"wpa9-accordion-content\" role=\"region\">\n\t\t\t<p>S\u00ed, en determinadas circunstancias. Este cargo puede variar en funci\u00f3n del proyecto y del historial del cliente. Nos aseguraremos de que tenga total claridad sobre todas las tarifas y posibles cargos por cancelaci\u00f3n antes de comenzar.<\/p>\n\t\t<\/div>\n\n\t<\/div>\n\t<div class=\"wpa9-accordion-panel\" id=\"wpa9-accordion-panel-cual-es-la-diferencia-entre-la-interpretacion-simultanea-y-la-consecutiva\">\n\n\t\t<div class=\"wpa9-accordion-toggler d-flex\" data-panel=\"cual-es-la-diferencia-entre-la-interpretacion-simultanea-y-la-consecutiva\" role=\"button\" aria-controls=\"wpa9-accordion-panel-cual-es-la-diferencia-entre-la-interpretacion-simultanea-y-la-consecutiva\" aria-expanded=\"false\">\n\n\t\t\t<div class=\"wpa9-accordion-icon wpa9-accordion-icon-open\"><\/div>\n\n\t\t\t<div class=\"wpa9-accordion-title\">\u00bfCu\u00e1l es la diferencia entre la interpretaci\u00f3n simult\u00e1nea y la consecutiva?<\/div>\n\n\t\t<\/div>\n\n\t\t<div class=\"wpa9-accordion-content\" role=\"region\">\n\t\t\t<p data-start=\"83\" data-end=\"388\">La interpretaci\u00f3n simult\u00e1nea, como su nombre indica, consiste en transmitir el mensaje en el idioma de destino pr\u00e1cticamente al mismo tiempo que se emite en el idioma original. Este tipo de interpretaci\u00f3n se utiliza habitualmente en eventos formales con presentaciones, ponentes y audiencias multiling\u00fces.<\/p>\n<p data-start=\"390\" data-end=\"651\" data-is-last-node=\"\" data-is-only-node=\"\">La interpretaci\u00f3n consecutiva se emplea normalmente en grupos m\u00e1s reducidos, cuando la comunicaci\u00f3n es m\u00e1s cercana y menos formal. El orador hace pausas tras unas pocas frases para permitir que el int\u00e9rprete traduzca oralmente el contenido al idioma de destino.<\/p>\n\t\t<\/div>\n\n\t<\/div>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><div id=\"pg-7642-7\"  class=\"panel-grid panel-has-style\" ><div class=\"siteorigin-panels-stretch panel-row-padding-none panel-row-style panel-row-style-for-7642-7\" data-stretch-type=\"full\" ><div id=\"pgc-7642-7-0\"  class=\"panel-grid-cell\" ><div id=\"panel-7642-7-0-0\" class=\"so-panel widget widget_wpa9-card-s panel-first-child panel-last-child\" data-index=\"14\" ><div class=\"mascot mascot-10 panel-widget-style panel-widget-style-for-7642-7-0-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-wpa9-card-s so-widget-wpa9-card-s-default-c93e1481a745-7642\"\n\t\t\t\n\t\t><div class=\"wpa9-card wpa9-card-s narrow negative\">\n\n\t<div class=\"wpa9-card-wrapper container\">\n\n\t\t<div class=\"wpa9-card-text\">\n\t\t\t<h2 class=\"wpa9-card-title\">Conozca los costes de interpretaci\u00f3n por adelantado<\/h2>\n\t\t\t<div class=\"wpa9-card-content\"><p style=\"text-align: center\">Facil\u00edtenos todos los detalles de su evento, ya sea presencial o remoto, y le proporcionaremos un presupuesto detallado y preciso antes de iniciar el proyecto. Puede confiar en nuestra experiencia para recomendarle el tipo de interpretaci\u00f3n m\u00e1s adecuado.<\/p>\n<\/div>\t\t<\/div>\n\n\t\t\t\t<div class=\"meta meta-buttons d-flex flex-row justify-content-center\">\n\t\t\t\t\t<a class=\"btn btn-negative show-inquiry-form\" href=\"https:\/\/skrivanek.com\/es\/consulta\/\" title=\"Enviar consulta\">Enviar consulta<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\n\t<\/div>\n\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Servicios de interpretaci\u00f3n Interpretaci\u00f3n de conferencias Trabaje con un socio de interpretaci\u00f3n que abarca m\u00e1s de 40 idiomas en varias combinaciones y que proporciona int\u00e9rpretes expertos donde los\u00a0necesite. Interpretaci\u00f3n de reuniones de negocios Con nuestro gran equipo de int\u00e9rpretes profesionales y experimentados, los asistentes a sus reuniones hablar\u00e1n el mismo idioma sin necesidad de conocerlo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-7642","page","type-page","status-publish","hentry"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/skrivanek.com\/es\/wp-json\/wp\/v2\/pages\/7642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skrivanek.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/skrivanek.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/skrivanek.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/skrivanek.com\/es\/wp-json\/wp\/v2\/comments?post=7642"}],"version-history":[{"count":3,"href":"https:\/\/skrivanek.com\/es\/wp-json\/wp\/v2\/pages\/7642\/revisions"}],"predecessor-version":[{"id":93324,"href":"https:\/\/skrivanek.com\/es\/wp-json\/wp\/v2\/pages\/7642\/revisions\/93324"}],"wp:attachment":[{"href":"https:\/\/skrivanek.com\/es\/wp-json\/wp\/v2\/media?parent=7642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}